{"id":10397,"date":"2017-02-08T00:40:42","date_gmt":"2017-02-07T23:40:42","guid":{"rendered":"http:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/"},"modified":"2017-02-08T01:25:33","modified_gmt":"2017-02-08T00:25:33","slug":"analisis","status":"publish","type":"page","link":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/","title":{"rendered":"An\u00e1lisis"},"content":{"rendered":"<p>El cambio clim\u00e1tico, profec\u00edas, o simplemente el curso natural del planeta, apuntan que el fin del mundo est\u00e1 cerca, o al menos tal como lo conocemos, de todas las posibilidades del supuesto fin, el m\u00e1s antiguo es el diluvio universal, que seg\u00fan la biblia, ya habr\u00eda ocurrido porque Dios, necesitaba hacer \u201cborr\u00f3n y cuenta nueva\u201d.<\/p>\n<p style=\"text-align: center;\"><em>Antes de nada dar las gracias a Cosmocover por cedernos el titulo para su an\u00e1lisis<\/em><\/p>\n<p><strong>Diluvion<\/strong> arranca cont\u00e1ndonos un cuento, sobre el castigo de los dioses, que asol\u00f3 a la humanidad, releg\u00e1ndolos a las profundidades del oc\u00e9ano, pero cuenta la leyenda en que dicho oc\u00e9ano, una diosa dejo un poder especial el cual, al ser descubierto, devolver\u00eda la tierra a la raza humana. Su historia y planteamiento bebe de diferentes conocidos de la literatura, \u00a0cine o la televisi\u00f3n, pel\u00edculas como<em> Waterworld<\/em> o libros como \u201cmil leguas de viaje submarino\u201d de Julio Verne, nos recuerdan a lo visto en este t\u00edtulo Indie.<\/p>\n<p><a href=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231408_1.jpg\" data-rel=\"prettyPhoto\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-10406 aligncenter\" src=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231408_1.jpg\" alt=\"\" width=\"582\" height=\"308\" srcset=\"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231408_1.jpg 1920w, https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231408_1-30x16.jpg 30w\" sizes=\"auto, (max-width: 582px) 100vw, 582px\" \/><\/a><\/p>\n<p>Aunque a nivel narrativo, es m\u00e1s fabula que trama, con esto me quiero referir, que en ning\u00fan momento, veremos una explicaci\u00f3n l\u00f3gica al castigo impartido por los dioses, quedando unas lagunas tan extensas en nuestro conocimiento, que ojo, no es malo, imita los cuentos de toda la vida donde el final es m\u00e1s importante que el conjunto de detalles, me explico, en el cuento de los tres cerditos, no tenemos una explicaci\u00f3n l\u00f3gica a porque los cerdos saben construir, ni porque el lobo sopla con tanta fuerza, no, no tiene sentido si lo analizamos desde un punto real, igual pasa con Diluvion, no tiene l\u00f3gica que a pesar de subir lo m\u00e1ximo en el escenario, este tiene un techo, haci\u00e9ndonos imposible ver el sol o el cielo, otras preguntas como por ejemplo, donde consiguen el O2, o como construyeron todo debajo del mar, son preguntas que a pesar de pasarte la aventura se da una importancia nula sobre \u00e9l, quedando relegado el argumento a la f\u00e1bula que se construye al inicio del juego.<\/p>\n<p>Clasificar Diluvion a un g\u00e9nero es sumamente complicado, su planteamiento de aventura convencional, se suma la estrategia y la aventura gr\u00e1fica tradicional. El manejo de la nave, no llega a niveles de simulaci\u00f3n, aunque se necesita cierto tiempo para dominar su movimiento, hemos de reconocer que el parche lanzado est\u00e9s d\u00edas ha mejorado con creces este defecto y facilitado algo mas su control.<\/p>\n<p>Antes de arrancar nuestra aventura, tendremos que escoger entre los 3 posibles submarinos que se nos ofrece, cada uno con un estilo bien diferenciado:<\/p>\n<p><a href=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206225825_1.jpg\" data-rel=\"prettyPhoto\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10407 alignleft\" src=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206225825_1.jpg\" alt=\"\" width=\"482\" height=\"255\" srcset=\"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206225825_1.jpg 1920w, https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206225825_1-30x16.jpg 30w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Glaciem MK<\/strong>: R\u00e1pida y \u00e1gil, pero d\u00e9bil en combate.<\/li>\n<li><strong>Iron Minnow:<\/strong> El equilibrado de los tres, no destaca sobre el resto en nada, pero es efectiva para empezar la primera partida.<\/li>\n<li><strong>Mariana:<\/strong> Una bestia en combate, pero lento como una tortuga.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Como he dicho necesitaras tiempo para dominar su manejo, algo err\u00e1tico, por la c\u00e1mara, nosotros el control nos ha sido m\u00e1s liviano con un mando, aunque aconsejamos no despegarse mucho del teclado o mejor dicho del rat\u00f3n, para otra parte que comentaremos m\u00e1s adelante. La parte de exploraci\u00f3n es enorme, tienes todo un oc\u00e9ano que explorar, con eso quiero decir, que, tanto en plano como en profundo, donde ser\u00e1 muy f\u00e1cil perderte, debido a la poca visibilidad, su laberintico escenario y un mapa que bien poco ayuda. \u00a0En plus de dar la sensaci\u00f3n de supervivencia, dispondremos de botellas de ox\u00edgeno, que conseguiremos de naves siniestradas o cuando atraquemos en los diferentes puestos que encontraremos por el extenso oc\u00e9ano, el ox\u00edgeno en ciertas partes ser\u00e1 un bien preciado, y tendremos que explorar bien todo el escenario para poder avanzar y no morir en el intento. Los momentos de combate ser\u00e1n lo m\u00e1s emocionante del t\u00edtulo, aunque no esperes combates \u00e9picos, dispondremos de una mirilla que controlaremos con el stick derecho, y disparamos con RT, contra veh\u00edculos enemigos o peligros de las profundidades, cuyos enfrentamientos bien avanzada la aventura, ser\u00e1n complicados y nos mandara en un abrir y cerrar de ojos a la pantalla de \u201creiniciar en ultimo Checkpoint\u201d.<\/p>\n<p>Cada vez que atraquemos la visi\u00f3n pasa del 3D a una visi\u00f3n 2D, que nos recordara a las aventuras graficas de anta\u00f1o o a una ilustraci\u00f3n de un cuento juvenil. En las paradas, podremos reclutar a m\u00e1s personal para nuestro submarino, comerciar, o sacar informaci\u00f3n a los habitantes de la misma para poder planificar nuestro pr\u00f3ximo viaje. Los tripulantes de nuestro nav\u00edo, los tendremos que contratar, al principio algunos lo har\u00e1n gratis, pero avanzado la aventura, algunos pedir\u00e1n salarios m\u00e1s altos que el propio Cristiano Ronaldo, eso si cada tripulante, estar\u00e1 especializado en una tarea de la nave, que van desde Sonar, mec\u00e1nico o Armero, tripulantes que podremos mejorar, despedir, o incluso pueden morir, si su nivel es bajo en algunas localizaciones de exploraci\u00f3n 2D.<\/p>\n<p><a href=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231358_1.jpg\" data-rel=\"prettyPhoto\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10408 alignright\" src=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231358_1.jpg\" alt=\"\" width=\"557\" height=\"295\" srcset=\"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231358_1.jpg 1920w, https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20170206231358_1-30x16.jpg 30w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/a>Gr\u00e1ficamente, no destaca en nada, es correcto, y la recreaci\u00f3n art\u00edstica de las profundidades del oc\u00e9ano, son m\u00e1s arte que realismo, no es nada malo este punto, pero es un aviso para \u201cnavegantes\u201d, en busca del realismo. Sus mapas son enormes y los detalles tanto de vegetaci\u00f3n y construcciones son correctos, con un aire muy Steam-punk, o neocl\u00e1sico. Nuestra nave tiene un dise\u00f1o muy simple, y los efectos de luz algunas veces ser\u00e1n lo m\u00e1s espectacular de este apartado. Los interiores son perfectas ilustraciones, donde nosotros no nos moveremos, y nuestro control se limita a pasar el cursor \/ puntero por encima de personas y objetos, con unas animaciones escasas, aunque me ha gustado esas animaciones tipo GIF, que tan buenos ratos nos hizo pasar en \u00e9pocas pasadas en las aventuras gr\u00e1ficas, esta parte se hace m\u00e1s liviano si disponemos del rat\u00f3n cerca, ya que con el mando se hace algo lento los movimientos del cursor, aunque no injugable.<\/p>\n<p><a href=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20160805102118_1.jpg\" data-rel=\"prettyPhoto\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10409 aligncenter\" src=\"http:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20160805102118_1.jpg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20160805102118_1.jpg 1000w, https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/20160805102118_1-30x17.jpg 30w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a>Su sonido, es para mi gusto el punto m\u00e1s logrado, su BSO, es simplemente fant\u00e1stica, con unos temas, escogidos a la perfecci\u00f3n, unidos a unos efectos de sonido perfectos para el juego. Como nota, no negativa , pero si necesario informar, es imprescindible el dominio del ingl\u00e9s, para poder enterarte de la historia, el cual es muy de f\u00e1bula, y llega a enganchar,\u00a0 pero con desconocimiento de la lengua brit\u00e1nica, perderemos demasiado detalles y nos cansaremos pronto de \u00e9l, aunque los desarrolladores no descartan su tradici\u00f3n si el p\u00fablico en general responde debidamente a en Steam y GOG, tiendas digitales donde lo puedes adquirir por menos de 20\u20ac un t\u00edtulo que podr\u00e1 darte si vas por el argumento, unas 14 horas de juego y muchos m\u00e1s si buscas todos los secretos que esconden las profundidades del mar.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Conclusi\u00f3n:<\/p>\n<p>Un juego Indie, que disfrutaras si tu dominio del ingl\u00e9s esta al d\u00eda, una aventura con mezcla de aventura gr\u00e1fica y aspecto Steam- Punk que nos recordara los cuentos de nuestra juventud. Una aventura que enamoraran a algunos y asustaran a otros, igual porque realmente lo que manejamos es una nave, y nuestro papel es el de comandante, y no de un personaje en concreto, y los escenarios de interiores, rompen un poco esa sensaci\u00f3n de libertad que tenemos al mando del submarino. Pero visto desde un\u00a0planteamiento m\u00e1s art\u00edstico, la sensaci\u00f3n que sus creadores quieren trasmitirnos, es la sensaci\u00f3n que a pesar del basto mundo, que se nos ofrece enfrente, nosotros como seres de tierra, seria nuestra prisi\u00f3n vivir bajo el agua, \u00bfquiz\u00e1s una lecci\u00f3n de cuidar lo que tenemos? Desc\u00fabrelo jugandolo&#8230;<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>El cambio clim\u00e1tico, profec\u00edas, o simplemente el curso natural del planeta, apuntan que el fin del mundo est\u00e1 cerca, o al menos tal como lo conocemos, de todas las posibilidades del supuesto fin, el m\u00e1s antiguo es el diluvio universal, que seg\u00fan la biblia, ya habr\u00eda ocurrido porque Dios, necesitaba hacer \u201cborr\u00f3n y cuenta nueva\u201d. Antes de nada dar las gracias a Cosmocover por cedernos el titulo para su an\u00e1lisis Diluvion arranca cont\u00e1ndonos un cuento, sobre el castigo de los dioses, que asol\u00f3 a la humanidad, releg\u00e1ndolos a las profundidades del oc\u00e9ano, pero cuenta la leyenda en que dicho oc\u00e9ano, una diosa dejo un poder especial el cual, al ser descubierto, devolver\u00eda la tierra a la raza humana. Su historia y planteamiento bebe de diferentes conocidos de la literatura, \u00a0cine o la televisi\u00f3n, pel\u00edculas como Waterworld o libros como \u201cmil leguas de viaje submarino\u201d de Julio Verne, nos recuerdan a lo visto en este t\u00edtulo Indie. Aunque a nivel narrativo, es m\u00e1s fabula que trama, con esto me quiero referir, que en ning\u00fan momento, veremos una explicaci\u00f3n l\u00f3gica al castigo impartido por los dioses, quedando unas lagunas tan extensas en nuestro conocimiento, que ojo, no es malo, imita los cuentos de toda la vida donde el final es m\u00e1s importante que el conjunto de detalles, me explico, en el cuento de los tres cerditos, no tenemos una explicaci\u00f3n l\u00f3gica a porque los cerdos saben construir, ni porque el lobo sopla con tanta fuerza, no, no tiene sentido si lo analizamos desde un punto real, igual pasa con Diluvion, no tiene l\u00f3gica que a pesar de subir lo m\u00e1ximo en el escenario, este tiene un techo, haci\u00e9ndonos imposible ver el sol o el cielo, otras preguntas como por ejemplo, donde consiguen el O2, o como construyeron todo debajo del mar, son preguntas que a pesar de pasarte la aventura se da una importancia nula sobre \u00e9l, quedando relegado el argumento a la f\u00e1bula que se construye al inicio del juego. Clasificar Diluvion a un g\u00e9nero es sumamente complicado, su planteamiento de aventura convencional, se suma la estrategia y la aventura gr\u00e1fica tradicional. El manejo de la nave, no llega a niveles de simulaci\u00f3n, aunque se necesita cierto tiempo para dominar su movimiento, hemos de reconocer que el parche lanzado est\u00e9s d\u00edas ha mejorado con creces este defecto y facilitado algo mas su control. Antes de arrancar nuestra aventura, tendremos que escoger entre los 3 posibles submarinos que se nos ofrece, cada uno con un estilo bien diferenciado: &nbsp; Glaciem MK: R\u00e1pida y \u00e1gil, pero d\u00e9bil en combate. Iron Minnow: El equilibrado de los tres, no destaca sobre el resto en nada, pero es efectiva para empezar la primera partida. Mariana: Una bestia en combate, pero lento como una tortuga. &nbsp; &nbsp; Como he dicho necesitaras tiempo para dominar su manejo, algo err\u00e1tico, por la c\u00e1mara, nosotros el control nos ha sido m\u00e1s liviano con un mando, aunque aconsejamos no despegarse mucho del teclado o mejor dicho del rat\u00f3n, para otra parte que comentaremos m\u00e1s adelante. La parte de exploraci\u00f3n es enorme, tienes todo un oc\u00e9ano que explorar, con eso quiero decir, que, tanto en plano como en profundo, donde ser\u00e1 muy f\u00e1cil perderte, debido a la poca visibilidad, su laberintico escenario y un mapa que bien poco ayuda. \u00a0En plus de dar la sensaci\u00f3n de supervivencia, dispondremos de botellas de ox\u00edgeno, que conseguiremos de naves siniestradas o cuando atraquemos en los diferentes puestos que encontraremos por el extenso oc\u00e9ano, el ox\u00edgeno en ciertas partes ser\u00e1 un bien preciado, y tendremos que explorar bien todo el escenario para poder avanzar y no morir en el intento. Los momentos de combate ser\u00e1n lo m\u00e1s emocionante del t\u00edtulo, aunque no esperes combates \u00e9picos, dispondremos de una mirilla que controlaremos con el stick derecho, y disparamos con RT, contra veh\u00edculos enemigos o peligros de las profundidades, cuyos enfrentamientos bien avanzada la aventura, ser\u00e1n complicados y nos mandara en un abrir y cerrar de ojos a la pantalla de \u201creiniciar en ultimo Checkpoint\u201d. Cada vez que atraquemos la visi\u00f3n pasa del 3D a una visi\u00f3n 2D, que nos recordara a las aventuras graficas de anta\u00f1o o a una ilustraci\u00f3n de un cuento juvenil. En las paradas, podremos reclutar a m\u00e1s personal para nuestro submarino, comerciar, o sacar informaci\u00f3n a los habitantes de la misma para poder planificar nuestro pr\u00f3ximo viaje. Los tripulantes de nuestro nav\u00edo, los tendremos que contratar, al principio algunos lo har\u00e1n gratis, pero avanzado la aventura, algunos pedir\u00e1n salarios m\u00e1s altos que el propio Cristiano Ronaldo, eso si cada tripulante, estar\u00e1 especializado en una tarea de la nave, que van desde Sonar, mec\u00e1nico o Armero, tripulantes que podremos mejorar, despedir, o incluso pueden morir, si su nivel es bajo en algunas localizaciones de exploraci\u00f3n 2D. Gr\u00e1ficamente, no destaca en nada, es correcto, y la recreaci\u00f3n art\u00edstica de las profundidades del oc\u00e9ano, son m\u00e1s arte que realismo, no es nada malo este punto, pero es un aviso para \u201cnavegantes\u201d, en busca del realismo. Sus mapas son enormes y los detalles tanto de vegetaci\u00f3n y construcciones son correctos, con un aire muy Steam-punk, o neocl\u00e1sico. Nuestra nave tiene un dise\u00f1o muy simple, y los efectos de luz algunas veces ser\u00e1n lo m\u00e1s espectacular de este apartado. Los interiores son perfectas ilustraciones, donde nosotros no nos moveremos, y nuestro control se limita a pasar el cursor \/ puntero por encima de personas y objetos, con unas animaciones escasas, aunque me ha gustado esas animaciones tipo GIF, que tan buenos ratos nos hizo pasar en \u00e9pocas pasadas en las aventuras gr\u00e1ficas, esta parte se hace m\u00e1s liviano si disponemos del rat\u00f3n cerca, ya que con el mando se hace algo lento los movimientos del cursor, aunque no injugable. Su sonido, es para mi gusto el punto m\u00e1s logrado, su BSO, es simplemente fant\u00e1stica, con unos temas, escogidos a la perfecci\u00f3n, unidos a unos efectos de sonido perfectos para el juego. Como nota, no negativa , pero si necesario informar, es imprescindible el dominio del ingl\u00e9s, para poder enterarte de la historia, el cual es muy de f\u00e1bula, y llega a enganchar,\u00a0 pero con desconocimiento de la lengua brit\u00e1nica, perderemos demasiado detalles y nos cansaremos pronto de \u00e9l, aunque los desarrolladores no descartan su tradici\u00f3n si el p\u00fablico en general responde debidamente a en Steam y GOG, tiendas digitales donde lo puedes adquirir por menos de 20\u20ac un t\u00edtulo que podr\u00e1 darte si vas por el argumento, unas 14 horas de juego y muchos m\u00e1s si buscas todos los secretos que esconden las profundidades del mar. &nbsp; Conclusi\u00f3n: Un juego Indie, que disfrutaras si tu dominio del ingl\u00e9s esta al d\u00eda, una aventura con mezcla de aventura gr\u00e1fica y aspecto Steam- Punk que nos recordara los cuentos de nuestra juventud. Una aventura que enamoraran a algunos y asustaran a otros, igual porque realmente lo que manejamos es una nave, y nuestro papel es el de comandante, y no de un personaje en concreto, y los escenarios de interiores, rompen un poco esa sensaci\u00f3n de libertad que tenemos al mando del submarino. Pero visto desde un\u00a0planteamiento m\u00e1s art\u00edstico, la sensaci\u00f3n que sus creadores quieren trasmitirnos, es la sensaci\u00f3n que a pesar del basto mundo, que se nos ofrece enfrente, nosotros como seres de tierra, seria nuestra prisi\u00f3n vivir bajo el agua, \u00bfquiz\u00e1s una lecci\u00f3n de cuidar lo que tenemos? Desc\u00fabrelo jugandolo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10403,"parent":10396,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"review-template.php","meta":{"footnotes":""},"tags":[943,944,133,374],"gp_hubs":[459,36,65],"fecha-lanzamiento":[],"genero":[],"recomendacion-edad":[],"compania":[],"publicado":[],"class_list":["post-10397","page","type-page","status-publish","has-post-thumbnail","tag-arachnid-studios","tag-diluvion","tag-pc","tag-steam","gp_hubs-analisis","gp_hubs-hub-pc","gp_hubs-hub-plataformas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An\u00e1lsis de Diluvion de Arachnid Studios STEAM<\/title>\n<meta name=\"description\" content=\"No he venido a predicar la biblia, para eso hay blogs mejores que yo\u2026 Hoy estamos aqu\u00ed reunidos para analizar Diluvion, el nuevo t\u00edtulo de Arachnid Studios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lsis de Diluvion de Arachnid Studios STEAM\" \/>\n<meta property=\"og:description\" content=\"No he venido a predicar la biblia, para eso hay blogs mejores que yo\u2026 Hoy estamos aqu\u00ed reunidos para analizar Diluvion, el nuevo t\u00edtulo de Arachnid Studios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/\" \/>\n<meta property=\"og:site_name\" content=\"LIMIT GAMERS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/limitgamers\/\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-08T00:25:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/diluvion-website-header.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1107\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@limit_gamers\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/\",\"url\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/\",\"name\":\"An\u00e1lsis de Diluvion de Arachnid Studios STEAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limitgamers.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/limitgamers.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/diluvion-website-header.png\",\"datePublished\":\"2017-02-07T23:40:42+00:00\",\"dateModified\":\"2017-02-08T00:25:33+00:00\",\"description\":\"No he venido a predicar la biblia, para eso hay blogs mejores que yo\u2026 Hoy estamos aqu\u00ed reunidos para analizar Diluvion, el nuevo t\u00edtulo de Arachnid Studios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/limitgamers.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/diluvion-website-header.png\",\"contentUrl\":\"https:\\\/\\\/limitgamers.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/diluvion-website-header.png\",\"width\":1107,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/analisis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/limitgamers.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diluvion\",\"item\":\"https:\\\/\\\/limitgamers.com\\\/index.php\\\/diluvion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"An\u00e1lisis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/limitgamers.com\\\/#website\",\"url\":\"https:\\\/\\\/limitgamers.com\\\/\",\"name\":\"LIMIT GAMERS\",\"description\":\"Bienvenido Gamers!\",\"publisher\":{\"@id\":\"https:\\\/\\\/limitgamers.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/limitgamers.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/limitgamers.com\\\/#organization\",\"name\":\"Limit Gamers\",\"url\":\"https:\\\/\\\/limitgamers.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/limitgamers.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/limitgamers.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/limitgamers.jpg\",\"contentUrl\":\"https:\\\/\\\/limitgamers.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/limitgamers.jpg\",\"width\":1712,\"height\":145,\"caption\":\"Limit Gamers\"},\"image\":{\"@id\":\"https:\\\/\\\/limitgamers.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/limitgamers\\\/\",\"https:\\\/\\\/x.com\\\/limit_gamers\",\"https:\\\/\\\/www.instagram.com\\\/limit_gamers\\\/\",\"http:\\\/\\\/www.youtube.com\\\/c\\\/Limitgamers\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lsis de Diluvion de Arachnid Studios STEAM","description":"No he venido a predicar la biblia, para eso hay blogs mejores que yo\u2026 Hoy estamos aqu\u00ed reunidos para analizar Diluvion, el nuevo t\u00edtulo de Arachnid Studios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/","og_locale":"es_ES","og_type":"article","og_title":"An\u00e1lsis de Diluvion de Arachnid Studios STEAM","og_description":"No he venido a predicar la biblia, para eso hay blogs mejores que yo\u2026 Hoy estamos aqu\u00ed reunidos para analizar Diluvion, el nuevo t\u00edtulo de Arachnid Studios.","og_url":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/","og_site_name":"LIMIT GAMERS","article_publisher":"https:\/\/www.facebook.com\/limitgamers\/","article_modified_time":"2017-02-08T00:25:33+00:00","og_image":[{"width":1107,"height":534,"url":"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/diluvion-website-header.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@limit_gamers","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/","url":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/","name":"An\u00e1lsis de Diluvion de Arachnid Studios STEAM","isPartOf":{"@id":"https:\/\/limitgamers.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/#primaryimage"},"image":{"@id":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/#primaryimage"},"thumbnailUrl":"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/diluvion-website-header.png","datePublished":"2017-02-07T23:40:42+00:00","dateModified":"2017-02-08T00:25:33+00:00","description":"No he venido a predicar la biblia, para eso hay blogs mejores que yo\u2026 Hoy estamos aqu\u00ed reunidos para analizar Diluvion, el nuevo t\u00edtulo de Arachnid Studios.","breadcrumb":{"@id":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/#primaryimage","url":"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/diluvion-website-header.png","contentUrl":"https:\/\/limitgamers.com\/wp-content\/uploads\/2017\/02\/diluvion-website-header.png","width":1107,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/limitgamers.com\/index.php\/diluvion\/analisis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/limitgamers.com\/"},{"@type":"ListItem","position":2,"name":"Diluvion","item":"https:\/\/limitgamers.com\/index.php\/diluvion\/"},{"@type":"ListItem","position":3,"name":"An\u00e1lisis"}]},{"@type":"WebSite","@id":"https:\/\/limitgamers.com\/#website","url":"https:\/\/limitgamers.com\/","name":"LIMIT GAMERS","description":"Bienvenido Gamers!","publisher":{"@id":"https:\/\/limitgamers.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/limitgamers.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/limitgamers.com\/#organization","name":"Limit Gamers","url":"https:\/\/limitgamers.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/limitgamers.com\/#\/schema\/logo\/image\/","url":"https:\/\/limitgamers.com\/wp-content\/uploads\/2016\/02\/limitgamers.jpg","contentUrl":"https:\/\/limitgamers.com\/wp-content\/uploads\/2016\/02\/limitgamers.jpg","width":1712,"height":145,"caption":"Limit Gamers"},"image":{"@id":"https:\/\/limitgamers.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/limitgamers\/","https:\/\/x.com\/limit_gamers","https:\/\/www.instagram.com\/limit_gamers\/","http:\/\/www.youtube.com\/c\/Limitgamers"]}]}},"_links":{"self":[{"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/pages\/10397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/comments?post=10397"}],"version-history":[{"count":0,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/pages\/10397\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/pages\/10396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/media\/10403"}],"wp:attachment":[{"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/media?parent=10397"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/tags?post=10397"},{"taxonomy":"gp_hubs","embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/gp_hubs?post=10397"},{"taxonomy":"fecha-lanzamiento","embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/fecha-lanzamiento?post=10397"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/genero?post=10397"},{"taxonomy":"recomendacion-edad","embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/recomendacion-edad?post=10397"},{"taxonomy":"compania","embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/compania?post=10397"},{"taxonomy":"publicado","embeddable":true,"href":"https:\/\/limitgamers.com\/index.php\/wp-json\/wp\/v2\/publicado?post=10397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}